{"id":1237,"count":1,"description":"","link":"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/","name":"digital leadership recruitment in UAE","slug":"digital-leadership-recruitment-in-uae","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>digital leadership recruitment in UAE Archives - H.R. International UAE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"digital leadership recruitment in UAE Archives - H.R. International UAE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/\" \/>\n<meta property=\"og:site_name\" content=\"H.R. International UAE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/\",\"url\":\"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/\",\"name\":\"digital leadership recruitment in UAE Archives - H.R. International UAE\",\"isPartOf\":{\"@id\":\"https:\/\/hrinternational.ae\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hrinternational.ae\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"digital leadership recruitment in UAE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hrinternational.ae\/blog\/#website\",\"url\":\"https:\/\/hrinternational.ae\/blog\/\",\"name\":\"H.R. International UAE\",\"description\":\"Blog\",\"publisher\":{\"@id\":\"https:\/\/hrinternational.ae\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hrinternational.ae\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hrinternational.ae\/blog\/#organization\",\"name\":\"H.R. International UAE\",\"url\":\"https:\/\/hrinternational.ae\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/hrinternational.ae\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hrinternational.ae\/blog\/wp-content\/uploads\/2024\/06\/cropped-hrinternational-uae.png\",\"contentUrl\":\"https:\/\/hrinternational.ae\/blog\/wp-content\/uploads\/2024\/06\/cropped-hrinternational-uae.png\",\"width\":502,\"height\":60,\"caption\":\"H.R. International UAE\"},\"image\":{\"@id\":\"https:\/\/hrinternational.ae\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"digital leadership recruitment in UAE Archives - H.R. International UAE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/","og_locale":"en_US","og_type":"article","og_title":"digital leadership recruitment in UAE Archives - H.R. International UAE","og_url":"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/","og_site_name":"H.R. International UAE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/","url":"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/","name":"digital leadership recruitment in UAE Archives - H.R. International UAE","isPartOf":{"@id":"https:\/\/hrinternational.ae\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/hrinternational.ae\/blog\/tag\/digital-leadership-recruitment-in-uae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hrinternational.ae\/blog\/"},{"@type":"ListItem","position":2,"name":"digital leadership recruitment in UAE"}]},{"@type":"WebSite","@id":"https:\/\/hrinternational.ae\/blog\/#website","url":"https:\/\/hrinternational.ae\/blog\/","name":"H.R. International UAE","description":"Blog","publisher":{"@id":"https:\/\/hrinternational.ae\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hrinternational.ae\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hrinternational.ae\/blog\/#organization","name":"H.R. International UAE","url":"https:\/\/hrinternational.ae\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hrinternational.ae\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hrinternational.ae\/blog\/wp-content\/uploads\/2024\/06\/cropped-hrinternational-uae.png","contentUrl":"https:\/\/hrinternational.ae\/blog\/wp-content\/uploads\/2024\/06\/cropped-hrinternational-uae.png","width":502,"height":60,"caption":"H.R. International UAE"},"image":{"@id":"https:\/\/hrinternational.ae\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hrinternational.ae\/blog\/wp-json\/wp\/v2\/tags\/1237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hrinternational.ae\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hrinternational.ae\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hrinternational.ae\/blog\/wp-json\/wp\/v2\/posts?tags=1237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}